{"id":2,"date":"2025-10-16T09:00:50","date_gmt":"2025-10-16T14:00:50","guid":{"rendered":"https:\/\/groovyhues1dev.wpenginepowered.com\/rogers-ar\/?page_id=2"},"modified":"2026-02-05T16:54:41","modified_gmt":"2026-02-05T22:54:41","slug":"home","status":"publish","type":"page","link":"https:\/\/www.groovyhues.com\/rogers-ar","title":{"rendered":"Home"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-2","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.groovyhues.com\/rogers-ar\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.groovyhues.com\/rogers-ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.groovyhues.com\/rogers-ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.groovyhues.com\/rogers-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.groovyhues.com\/rogers-ar\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":0,"href":"https:\/\/www.groovyhues.com\/rogers-ar\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.groovyhues.com\/rogers-ar\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}